{"id":4034,"date":"2026-02-17T20:10:41","date_gmt":"2026-02-17T19:10:41","guid":{"rendered":"https:\/\/hotel-chasseral.ch\/?post_type=events&#038;p=4034"},"modified":"2026-02-22T20:29:08","modified_gmt":"2026-02-22T19:29:08","slug":"der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern","status":"publish","type":"events","link":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/","title":{"rendered":"Der September ist der beste Monat, um die Milchstrasse zu bewundern"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\"><strong>Datum:<\/strong><br \/>Samstag, 12.09.2026<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Zeit:<\/strong><br \/>19.00 \u2013 23.30 Uhr<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong><strong><strong><strong>Programm \/ Inhalt \/ Details<\/strong><\/strong><\/strong>:<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Der September ist der beste Monat, um die Milchstrasse zu bewundern. Zu Beginn vom Anlass erhalten Sie von unseren Experten Erkl\u00e4rungen, was wir alles in unserer Milchstrasse entdecken k\u00f6nnen. Nach dem 3-Gang Abendessen, widmen wir uns dann der Beobachtung der Sch\u00e4tze des Nachthimmels, wie Sternhaufen oder \u00dcberreste von Sternen in Form von Gasnebel. Auch der spektakul\u00e4re Planet Saturn wird den Nachthimmel schm\u00fccken. Bei einem Sternenbilderrundgang werden Sie zudem die markantesten Sternbilder des Herbstes kennenlernen. Wer m\u00f6chte kann nach dem Anlass vor Ort im Hotel \u00fcbernachten.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Programm des Abends:<br \/><\/strong>19:00-21:00 Welcome Drink &amp; Abendessen<br \/>21:00-22:00 Interaktive Pr\u00e4sentation<br \/>22:00-23:30 Beobachtung des Nachthimmels durch professionelle Teleskope<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Men\u00fc:<br \/><\/strong>Gemischter Saison-Salat<br \/>***<br \/>Gebratenes Pouletsupr\u00eame, Waldpilzsauce<br \/>Pommes Mousseline und saisonales Gem\u00fcse<br \/>***<br \/>Dunkles Schokoladenmousse<br \/>Ger\u00f6stete Haselnussst\u00fccke<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Preis:<br \/>Der Preis beinhaltet die Teilnahme am Anlass, das oben aufgef\u00fchrte Abendessen, 1 Welcome-Drink, Mineralwasser und Kaffee\/Espresso w\u00e4hrend dem Abendessen. <\/strong>Zus\u00e4tzliche oder andere Getr\u00e4nke sind individuell zus\u00e4tzlich zu bezahlen.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Erwachsene: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0CHF 98.- pro Person<br \/>Kinder (0-12 Jahre):\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 CHF 57.- pro Kind (jeweils \u00bd Portion des Men\u00fcs)<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>\u00dcbernachtungs-M\u00f6glichkeiten:<br \/><\/strong>Sollten Sie eine \u00dcbernachtung im Hotel-Zimmer oder im Mehrbettzimmer buchen wollen, k\u00f6nnen Sie diese direkt auf der Webseite des Hotels buchen: <a href=\"https:\/\/hotel-chasseral.ch\/de\/hotel-restaurant\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/hotel-chasseral.ch\/de\/hotel-restaurant\/<\/strong><\/a>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Wichtige Hinweise:<\/strong><br \/>-Die Astroabende werden in Kooperation mit <a href=\"http:\/\/www.astroevents.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Astro Events<\/a> durchgef\u00fchrt und finden in <strong>deutscher &amp; franz\u00f6sischer Sprache<\/strong> statt.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">-Der Anlass findet bei jeder Witterung statt. Im Falle von schlechtem Wetter wird die Beobachtung durch ein attraktives Alternativprogramm ersetzt.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">-Alle Bestellungen sind verbindlich. Tickets k\u00f6nnen nicht r\u00fcckerstattet werden.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">-Die Mindest-Teilnehmerzahl liegt bei 16 Personen. Sollte diese Zahl nicht erreicht werden, erfolgt die Stornierung seitens Veranstalter sp\u00e4testens 7 Tage vor dem Anlass. Die Teilnahmegeb\u00fchr wird in diesem Fall r\u00fcckerstattet.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">-Die Anzahl Pl\u00e4tze sind beschr\u00e4nkt und werden nach Bestelleingang ber\u00fccksichtigt.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Eine Anmeldung ist obligatorisch via:<br \/><a href=\"https:\/\/eventfrog.ch\/de\/p\/fuehrungen-vortraege\/vortrag\/3-astronomie-abend-chasseral-3-soiree-astronomique-7422419027409027176.html\" target=\"_blank\" rel=\"noopener\">https:\/\/eventfrog.ch\/de\/p\/fuehrungen-vortraege\/vortrag\/3-astronomie-abend-chasseral-3-soiree-astronomique-7422419027409027176.html<\/a><br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Ort:<\/strong><br \/>Hotel Restaurant Chasseral, Route de Chasseral 124, 2518 Nods<br \/>(Google Maps:\u00a0<a href=\"https:\/\/maps.app.goo.gl\/8auEz2Z1vigroxA77\">https:\/\/maps.app.goo.gl\/8auEz2Z1vigroxA77<\/a>)<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong><strong><strong><strong>Kontakt &amp; \u00d6ffnungszeiten Hotel + Restaurant<\/strong>:<\/strong><\/strong><\/strong><br \/>Link:\u00a0<a href=\"https:\/\/hotel-chasseral.ch\/de\/kontakt-anreise\/\">https:\/\/hotel-chasseral.ch\/de\/kontakt-anreise<\/a>\/<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Am Samstag, 12.09.2026 &#8211; Der September ist der beste Monat, um die Milchstrasse zu bewundern. Zu Beginn vom Anlass erhalten Sie von unseren Experten Erkl\u00e4rungen, was wir alles in unserer Milchstrasse entdecken k\u00f6nnen.<\/p>\n","protected":false},"featured_media":4036,"template":"","meta":{"_acf_changed":true},"categories":[42],"class_list":["post-4034","events","type-events","status-publish","has-post-thumbnail","hentry","category-events"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral\" \/>\n<meta property=\"og:description\" content=\"Am Samstag, 12.09.2026 - Der September ist der beste Monat, um die Milchstrasse zu bewundern. Zu Beginn vom Anlass erhalten Sie von unseren Experten Erkl\u00e4rungen, was wir alles in unserer Milchstrasse entdecken k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/\" \/>\n<meta property=\"og:site_name\" content=\"Chasseral\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T19:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/Astronomie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"821\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/\",\"name\":\"Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/Astronomie.jpg\",\"datePublished\":\"2026-02-17T19:10:41+00:00\",\"dateModified\":\"2026-02-22T19:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/Astronomie.jpg\",\"contentUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/Astronomie.jpg\",\"width\":1001,\"height\":821},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/events\\\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/hotel-chasseral.ch\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Der September ist der beste Monat, um die Milchstrasse zu bewundern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\",\"name\":\"Chasseral\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#organization\",\"name\":\"Chasseral\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/chasseral-main-min.svg\",\"contentUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/chasseral-main-min.svg\",\"width\":175,\"height\":60,\"caption\":\"Chasseral\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/","og_locale":"de_DE","og_type":"article","og_title":"Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral","og_description":"Am Samstag, 12.09.2026 - Der September ist der beste Monat, um die Milchstrasse zu bewundern. Zu Beginn vom Anlass erhalten Sie von unseren Experten Erkl\u00e4rungen, was wir alles in unserer Milchstrasse entdecken k\u00f6nnen.","og_url":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/","og_site_name":"Chasseral","article_modified_time":"2026-02-22T19:29:08+00:00","og_image":[{"width":1001,"height":821,"url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/Astronomie.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/","url":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/","name":"Der September ist der beste Monat, um die Milchstrasse zu bewundern &#8226; Chasseral","isPartOf":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/#primaryimage"},"image":{"@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/#primaryimage"},"thumbnailUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/Astronomie.jpg","datePublished":"2026-02-17T19:10:41+00:00","dateModified":"2026-02-22T19:29:08+00:00","breadcrumb":{"@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/#primaryimage","url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/Astronomie.jpg","contentUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/Astronomie.jpg","width":1001,"height":821},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-chasseral.ch\/de\/events\/der-september-ist-der-beste-monat-um-die-milchstrasse-zu-bewundern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotel-chasseral.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/hotel-chasseral.ch\/events\/"},{"@type":"ListItem","position":3,"name":"Der September ist der beste Monat, um die Milchstrasse zu bewundern"}]},{"@type":"WebSite","@id":"https:\/\/hotel-chasseral.ch\/de\/#website","url":"https:\/\/hotel-chasseral.ch\/de\/","name":"Chasseral","description":"","publisher":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-chasseral.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hotel-chasseral.ch\/de\/#organization","name":"Chasseral","url":"https:\/\/hotel-chasseral.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/chasseral-main-min.svg","contentUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/chasseral-main-min.svg","width":175,"height":60,"caption":"Chasseral"},"image":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/events\/4034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/media\/4036"}],"wp:attachment":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/media?parent=4034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/categories?post=4034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}