{"id":3436,"date":"2025-09-26T16:39:25","date_gmt":"2025-09-26T14:39:25","guid":{"rendered":"https:\/\/hotel-chasseral.ch\/?p=3436"},"modified":"2025-09-26T18:10:51","modified_gmt":"2025-09-26T16:10:51","slug":"rueckblick-grand-prix-chasseral-ein-voller-erfolg","status":"publish","type":"post","link":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/","title":{"rendered":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><strong><strong>Das Radrennen 1. Grand Prix Chasseral, welcher zum 100-Jahr-Jubil\u00e4um des Hotel-Restaurant Chasseral am 24. August 2025 durchgef\u00fchrt wurde, war mit 157 eingeschriebenen Teilnehmer, gl\u00fccklichen Siegern, unvergleichlich sch\u00f6nen Pokalen sowie \u00fcber hundert begeisterten Zuschauern ein voller Erfolg! Die erste Ausgabe bringt der Region Chasseral auch langfristig einen Nutzen durch die Spende des Gewinns von CHF 2\u2018200.- an den Pump-Track Bas-Lac.<\/strong><\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Radrennen Grand Prix Chasseral mit einzigartigen Aussichten wurde vom Hotel Restaurant Chasseral in Zusammenarbeit mit dem Club Cycliste du Littoral und der White Carpet GmbH realisiert. Dank den Sponsoren Cycles Prof L\u00fcthi S\u00e0rl, Forest Jump und TCS Training Ligni\u00e8res konnten den drei besten Teilnehmer jeder Kategorie (mit Ausnahme der Kategorie Populaire) zudem einzigartige Kristall-Pokale mit dem 3D-Motives des Sendeturms sowie weitere attraktive Preise abgegeben werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit total 157 eingeschriebenen Teilnehmern in den Kategorien Juniors Dames, Dames, Juniors Hommes, Hommes, Masters Hommes, Plus de 80kg+ und Populaire wurden die Erwartungen f\u00fcr eine Erstausgabe bei Weitem \u00fcbertroffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit einer Distanz von 11km und 150m und einem H\u00f6henunterschied von 749hm wurde die Ikone des Schweizer Jurabogens mit unglaublich hohem Tempo \u00aberobert\u00bb. Beim Start beim TCS Center in Ligni\u00e8res und insbesondere beim einzigartigen Hotel Restaurant &#8211; wo sich das Ziel befand &#8211; s\u00e4umten \u00fcber hundert Zuschauer die Strassen. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Gewinn aus dem Event in H\u00f6he von CHF 2&#8217;200.- werden vom Hotel Restaurant Chasseral und dem Club Cycliste du Littoral f\u00fcr das Projekt des Pump-Track Bas-Lac (Association Pumptrack Bas-Lac, St-Blaise \/ <a href=\"https:\/\/pumptrackbaslac.ch\/\">https:\/\/pumptrackbaslac.ch<\/a>) zur Verf\u00fcgung gestellt, um das Projekt zugunsten der Jugend realisieren zu k\u00f6nnen. Das f\u00f6rdert den Radsport in der ganzen Region Chasseral nachhaltig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Details zum Event:<\/strong><br>Streckenplan &amp; H\u00f6henprofil: <a href=\"https:\/\/www.strava.com\/routes\/3349432846731096220\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.strava.com\/routes\/3349432846731096220<\/a><br>Startliste: <a href=\"https:\/\/cclittoral.ch\/activites\/grand_prix_chasseral.php?lang=de#liste\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cclittoral.ch\/activites\/grand_prix_chasseral.php?lang=de#liste<\/a><br>Ergebnisse: <a href=\"https:\/\/cclittoral.ch\/activites\/grand_prix_chasseral.php?lang=de#resultats\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cclittoral.ch\/activites\/grand_prix_chasseral.php?lang=de#resultats<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Foto-R\u00fcckblick zum Event:<\/strong><br><a href=\"https:\/\/www.blaurockpix.ch\/2617768\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.blaurockpix.ch\/2617768<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Video-R\u00fcckblick zum Event:<\/strong><br><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe class=\"lazyload\" title=\"R\u00fcckblick \/ R\u00e9trospective: GRAND PRIX CHASSERAL - CYCLISTE \/ VELO 2025\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/U3te6Q7Yp3g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Das Radrennen 1. Grand Prix Chasseral, welcher zum 100-Jahr-Jubil\u00e4um des Hotel-Restaurant Chasseral am 24. August 2025 durchgef\u00fchrt wurde, war mit 157 eingeschriebenen Teilnehmer, gl\u00fccklichen Siegern, unvergleichlich sch\u00f6nen Pokalen sowie \u00fcber hundert begeisterten Zuschauern ein voller Erfolg! Die erste Ausgabe bringt der Region Chasseral auch langfristig einen Nutzen durch die Spende des Gewinns von CHF 2\u2018200.- an den Pump-Track Bas-Lac.<\/p>\n","protected":false},"author":8,"featured_media":3442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[42,18,33],"tags":[],"class_list":["post-3436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-hotel-restaurant","category-hotel-restaurant-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral\" \/>\n<meta property=\"og:description\" content=\"Das Radrennen 1. Grand Prix Chasseral, welcher zum 100-Jahr-Jubil\u00e4um des Hotel-Restaurant Chasseral am 24. August 2025 durchgef\u00fchrt wurde, war mit 157 eingeschriebenen Teilnehmer, gl\u00fccklichen Siegern, unvergleichlich sch\u00f6nen Pokalen sowie \u00fcber hundert begeisterten Zuschauern ein voller Erfolg! Die erste Ausgabe bringt der Region Chasseral auch langfristig einen Nutzen durch die Spende des Gewinns von CHF 2\u2018200.- an den Pump-Track Bas-Lac.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/\" \/>\n<meta property=\"og:site_name\" content=\"Chasseral\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T14:39:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T16:10:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joris Zahnd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joris Zahnd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/\"},\"author\":{\"name\":\"Joris Zahnd\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/person\\\/2dc6bedd233001b795d1b63d5cd7b887\"},\"headline\":\"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg !\",\"datePublished\":\"2025-09-26T14:39:25+00:00\",\"dateModified\":\"2025-09-26T16:10:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/J4A0149-klein-scaled.jpg\",\"articleSection\":[\"Events\",\"Hotel &amp; Restaurant\",\"H\u00f4tel &amp; Restaurant\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/\",\"name\":\"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/J4A0149-klein-scaled.jpg\",\"datePublished\":\"2025-09-26T14:39:25+00:00\",\"dateModified\":\"2025-09-26T16:10:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/J4A0149-klein-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/J4A0149-klein-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\",\"name\":\"Chasseral\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#organization\",\"name\":\"Chasseral\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/chasseral-main-min.svg\",\"contentUrl\":\"https:\\\/\\\/hotel-chasseral.ch\\\/wp-content\\\/uploads\\\/chasseral-main-min.svg\",\"width\":175,\"height\":60,\"caption\":\"Chasseral\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotel-chasseral.ch\\\/de\\\/#\\\/schema\\\/person\\\/2dc6bedd233001b795d1b63d5cd7b887\",\"name\":\"Joris Zahnd\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral","og_description":"Das Radrennen 1. Grand Prix Chasseral, welcher zum 100-Jahr-Jubil\u00e4um des Hotel-Restaurant Chasseral am 24. August 2025 durchgef\u00fchrt wurde, war mit 157 eingeschriebenen Teilnehmer, gl\u00fccklichen Siegern, unvergleichlich sch\u00f6nen Pokalen sowie \u00fcber hundert begeisterten Zuschauern ein voller Erfolg! Die erste Ausgabe bringt der Region Chasseral auch langfristig einen Nutzen durch die Spende des Gewinns von CHF 2\u2018200.- an den Pump-Track Bas-Lac.","og_url":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/","og_site_name":"Chasseral","article_published_time":"2025-09-26T14:39:25+00:00","article_modified_time":"2025-09-26T16:10:51+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg","type":"image\/jpeg"}],"author":"Joris Zahnd","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joris Zahnd","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#article","isPartOf":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/"},"author":{"name":"Joris Zahnd","@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/person\/2dc6bedd233001b795d1b63d5cd7b887"},"headline":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg !","datePublished":"2025-09-26T14:39:25+00:00","dateModified":"2025-09-26T16:10:51+00:00","mainEntityOfPage":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/"},"wordCount":336,"publisher":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#organization"},"image":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#primaryimage"},"thumbnailUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg","articleSection":["Events","Hotel &amp; Restaurant","H\u00f4tel &amp; Restaurant"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/","url":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/","name":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg ! &#8226; Chasseral","isPartOf":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#primaryimage"},"image":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#primaryimage"},"thumbnailUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg","datePublished":"2025-09-26T14:39:25+00:00","dateModified":"2025-09-26T16:10:51+00:00","breadcrumb":{"@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#primaryimage","url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg","contentUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/J4A0149-klein-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-chasseral.ch\/de\/rueckblick-grand-prix-chasseral-ein-voller-erfolg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotel-chasseral.ch\/de\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckblick: Grand Prix Chasseral \u2013 ein voller Erfolg !"}]},{"@type":"WebSite","@id":"https:\/\/hotel-chasseral.ch\/de\/#website","url":"https:\/\/hotel-chasseral.ch\/de\/","name":"Chasseral","description":"","publisher":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-chasseral.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hotel-chasseral.ch\/de\/#organization","name":"Chasseral","url":"https:\/\/hotel-chasseral.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/chasseral-main-min.svg","contentUrl":"https:\/\/hotel-chasseral.ch\/wp-content\/uploads\/chasseral-main-min.svg","width":175,"height":60,"caption":"Chasseral"},"image":{"@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hotel-chasseral.ch\/de\/#\/schema\/person\/2dc6bedd233001b795d1b63d5cd7b887","name":"Joris Zahnd"}]}},"_links":{"self":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/posts\/3436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/comments?post=3436"}],"version-history":[{"count":4,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/posts\/3436\/revisions"}],"predecessor-version":[{"id":3457,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/posts\/3436\/revisions\/3457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/media\/3442"}],"wp:attachment":[{"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/media?parent=3436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/categories?post=3436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel-chasseral.ch\/de\/wp-json\/wp\/v2\/tags?post=3436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}